{"id":5567,"date":"2026-03-23T17:56:00","date_gmt":"2026-03-23T20:56:00","guid":{"rendered":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/comissao-aprova-repasse-de-parte-dos-royalties-da-mineracao-a-projetos-ambientais-locais-noticias\/"},"modified":"2026-03-23T17:56:00","modified_gmt":"2026-03-23T20:56:00","slug":"comissao-aprova-repasse-de-parte-dos-royalties-da-mineracao-a-projetos-ambientais-locais-noticias","status":"publish","type":"post","link":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/comissao-aprova-repasse-de-parte-dos-royalties-da-mineracao-a-projetos-ambientais-locais-noticias\/","title":{"rendered":"Comiss\u00e3o aprova repasse de parte dos royalties da minera\u00e7\u00e3o a projetos ambientais locais &#8211; Not\u00edcias"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<div>\n<p class=\"g-artigo__data-hora\">\n\t\t\t\t\t\t\t\t\t\t\t23\/03\/2026 &#8211; 17:21 \u00a0\n\t\t\t\t\t\t\t\t\t\t<\/p>\n<div id=\"image-container-1256646\" class=\"image-container\" style=\"float: none; margin: 45px 0px; width: 100%;\" data-midia=\"1256646\">\n<p><em>Kayo Magalh\u00e3es\/C\u00e2mara dos Deputados<\/em><\/p>\n<p>Deputado Joaquim Passarinho, relator do projeto de lei<\/p>\n<\/p><\/div>\n<p>A Comiss\u00e3o de Minas e Energia da C\u00e2mara dos Deputados aprovou projeto de lei que repassa uma fatia dos royalties da minera\u00e7\u00e3o pagos a munic\u00edpios e ao Distrito Federal para \u00f3rg\u00e3os ambientais locais e para projetos de recupera\u00e7\u00e3o de \u00e1reas degradadas por minera\u00e7\u00e3o irregular. O texto aprovado altera a lei que regulamenta a Compensa\u00e7\u00e3o Financeira pela Explora\u00e7\u00e3o de Recursos Minerais (CFEM).<\/p>\n<p>Pela proposta, dos 60% arrecadados com a CFEM e destinados ao Distrito Federal e munic\u00edpios, pelo menos, 5% dever\u00e3o ser repassados ao \u00f3rg\u00e3o de meio ambiente local para a recupera\u00e7\u00e3o de \u00e1reas degradadas pela minera\u00e7\u00e3o irregular. Quando esse \u00f3rg\u00e3o n\u00e3o existir, os recursos ser\u00e3o aplicados em projetos ambientais com esse prop\u00f3sito.<\/p>\n<p>A comiss\u00e3o aprovou o <a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1061453-proposta-destina-parte-da-cfem-aos-orgaos-locais-de-meio-ambiente\">Projeto de Lei 1277\/24<\/a>, do deputado Duarte Gon\u00e7alves Jr (Republicanos-MG), com as emendas do relator, deputado Joaquim Passarinho (PL-PA). O texto original previa apenas o repasse para o \u00f3rg\u00e3o ambiental local.<\/p>\n<p>\u201c\u00c9 necess\u00e1rio assegurar que esses recursos adicionais para a prote\u00e7\u00e3o do meio ambiente sejam dirigidos para a recupera\u00e7\u00e3o de \u00e1reas degradadas ilegalmente\u201d, ressaltou o relator.<\/p>\n<p>Passarinho lembrou que, em 2025, o total arrecadado com a CFEM foi de R$ 7,9 bilh\u00f5es. Nesse ano, por exemplo, os 5% para os \u00f3rg\u00e3os ambientais locais poderiam ter somado cerca de R$ 230 milh\u00f5es a mais para recupera\u00e7\u00e3o de \u00e1reas, conforme o projeto.<\/p>\n<p><strong>Pr\u00f3ximas etapas<\/strong><br \/>A proposta ser\u00e1 ainda analisada, em <span id=\"4322\" class=\"termoGlossario\" title=\"Rito de tramita\u00e7\u00e3o pelo qual o projeto \u00e9 votado apenas pelas comiss\u00f5es designadas para analis\u00e1-lo, dispensada a delibera\u00e7\u00e3o do Plen\u00e1rio. O projeto perde o car\u00e1ter conclusivo se houver decis\u00e3o divergente entre as comiss\u00f5es ou se, independentemente de ser aprovado ou rejeitado, houver recurso assinado por 52 deputados para a aprecia\u00e7\u00e3o da mat\u00e9ria no Plen\u00e1rio.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">car\u00e1ter conclusivo<\/span>, pelas comiss\u00f5es de Meio Ambiente e Desenvolvimento Sustent\u00e1vel; de Finan\u00e7as e Tributa\u00e7\u00e3o; e de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania. Para virar lei, o texto deve ser aprovado pela C\u00e2mara e pelo Senado.<\/p>\n<p style=\"font-size: 0.8rem; font-weight: 700;\">Reportagem \u2013 Murilo Souza<br \/>Edi\u00e7\u00e3o \u2013 Roberto Seabra<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1256598-comissao-aprova-repasse-de-parte-dos-royalties-da-mineracao-a-projetos-ambientais-locais\/\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>23\/03\/2026 &#8211; 17:21 \u00a0 Kayo Magalh\u00e3es\/C\u00e2mara dos Deputados Deputado Joaquim Passarinho, relator do projeto de lei A Comiss\u00e3o de Minas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[10],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/5567"}],"collection":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=5567"}],"version-history":[{"count":0,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/5567\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/5568"}],"wp:attachment":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=5567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=5567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=5567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}