{"id":5526,"date":"2026-03-21T02:33:02","date_gmt":"2026-03-21T05:33:02","guid":{"rendered":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/comissao-aprova-aumento-de-pena-para-quem-retem-cartao-de-pessoa-com-deficiencia-noticias\/"},"modified":"2026-03-21T02:33:02","modified_gmt":"2026-03-21T05:33:02","slug":"comissao-aprova-aumento-de-pena-para-quem-retem-cartao-de-pessoa-com-deficiencia-noticias","status":"publish","type":"post","link":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/comissao-aprova-aumento-de-pena-para-quem-retem-cartao-de-pessoa-com-deficiencia-noticias\/","title":{"rendered":"Comiss\u00e3o aprova aumento de pena para quem ret\u00e9m cart\u00e3o de pessoa com defici\u00eancia &#8211; Not\u00edcias"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<div>\n<p class=\"g-artigo__data-hora\">\n                      19\/03\/2026 &#8211; 12:41 \u00a0\n                    <\/p>\n<div id=\"image-container-1255603\" class=\"image-container\" style=\"float: none; margin: 45px 0px; width: 100%;\" data-midia=\"1255603\">\n<p><em>Vinicius Loures \/ C\u00e2mara dos Deputados<\/em><\/p>\n<p>Andreia Siqueira: penalidade atual passa mensagem de delito de menor import\u00e2ncia<\/p>\n<\/p><\/div>\n<p>A Comiss\u00e3o de Defesa dos Direitos das Pessoas com Defici\u00eancia da C\u00e2mara dos Deputados aprovou projeto de lei que endurece a puni\u00e7\u00e3o para o crime de reten\u00e7\u00e3o ou utiliza\u00e7\u00e3o indevida de cart\u00e3o magn\u00e9tico ou meio eletr\u00f4nico de pessoa com defici\u00eancia destinados ao recebimento de benef\u00edcios e pens\u00f5es, entre outros.<\/p>\n<p>A proposta altera o <a href=\"https:\/\/www2.camara.leg.br\/legin\/fed\/lei\/2015\/lei-13146-6-julho-2015-781174-norma-pl.html\">Estatuto da Pessoa com Defici\u00eancia<\/a>\u00a0para elevar a san\u00e7\u00e3o para <span id=\"4303\" class=\"termoGlossario\" title=\"A reclus\u00e3o \u00e9 a mais severa entre as penas privativas de liberdade. Destina-se a crimes dolosos (com inten\u00e7\u00e3o).\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">reclus\u00e3o<\/span>, de dois a cinco anos, e multa. Atualmente, a legisla\u00e7\u00e3o prev\u00ea para a conduta pena de <span id=\"4293\" class=\"termoGlossario\" title=\"Pena privativa de liberdade que se cumpre em regime aberto ou semiaberto, salvo transfer\u00eancia excepcional para o regime fechado. \u00c9 menos severa que a reclus\u00e3o e mais rigorosa que a pris\u00e3o simples.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">deten\u00e7\u00e3o<\/span>, de seis meses a dois anos, e multa.<\/p>\n<p>A relatora da mat\u00e9ria, deputada Andreia Siqueira (MDB-PA), apresentou um <span id=\"4098\" class=\"termoGlossario\" title=\"Nome que se d\u00e1 ao texto que altera substancialmente o conte\u00fado original da proposta. O substitutivo \u00e9 apresentado pelo relator e tem prefer\u00eancia na vota\u00e7\u00e3o sobre o projeto original.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">substitutivo<\/span> ao Projeto de Lei 6557\/25, do deputado Andr\u00e9 Fernandes (PL-CE). A nova reda\u00e7\u00e3o traz uma altera\u00e7\u00e3o t\u00e9cnica que n\u00e3o modifica o objetivo do projeto original.<\/p>\n<p>A relatora defendeu o rigor na lei para proteger a autonomia e a dignidade das v\u00edtimas de um crime muitas vezes praticado por familiares.<\/p>\n<p>\u201cA atual penalidade envia uma mensagem para a sociedade de que enganar uma pessoa com defici\u00eancia, furtando sua renda por meio do acesso ao cart\u00e3o eletr\u00f4nico, \u00e9 um delito de menor import\u00e2ncia\u201d, considerou a parlamentar.<\/p>\n<p>Andreia Siqueira disse que elevar a san\u00e7\u00e3o para os patamares da reclus\u00e3o sinaliza o compromisso do Estado com a prote\u00e7\u00e3o das pessoas mais vulner\u00e1veis.<\/p>\n<p><strong>Pr\u00f3ximos passos<\/strong><br \/>O projeto ainda ser\u00e1 analisado pela Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania, antes de seguir para a aprecia\u00e7\u00e3o do Plen\u00e1rio da C\u00e2mara.<\/p>\n<p>Para virar lei, precisa ser aprovado pelos deputados e pelos senadores e sancionado pelo presidente da Rep\u00fablica.<\/p>\n<p style=\"font-size: 0.8rem; font-weight: 700;\">Reportagem \u2013 No\u00e9li Nobre<br \/>Edi\u00e7\u00e3o \u2013 Marcia Becker<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1255483-comissao-aprova-aumento-de-pena-para-quem-retem-cartao-de-pessoa-com-deficiencia\/\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>19\/03\/2026 &#8211; 12:41 \u00a0 Vinicius Loures \/ C\u00e2mara dos Deputados Andreia Siqueira: penalidade atual passa mensagem de delito de menor [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5527,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[20],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/5526"}],"collection":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=5526"}],"version-history":[{"count":0,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/5526\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/5527"}],"wp:attachment":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=5526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=5526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=5526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}