{"id":5414,"date":"2026-03-17T06:16:19","date_gmt":"2026-03-17T09:16:19","guid":{"rendered":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/comissao-aprova-protecao-a-mulheres-antes-de-revogar-medidas-noticias\/"},"modified":"2026-03-17T06:16:19","modified_gmt":"2026-03-17T09:16:19","slug":"comissao-aprova-protecao-a-mulheres-antes-de-revogar-medidas-noticias","status":"publish","type":"post","link":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/comissao-aprova-protecao-a-mulheres-antes-de-revogar-medidas-noticias\/","title":{"rendered":"Comiss\u00e3o aprova prote\u00e7\u00e3o a mulheres antes de revogar medidas &#8211; Not\u00edcias"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"g-artigo__data-hora\">\n                      16\/03\/2026 &#8211; 11:00 \u00a0\n                    <\/p>\n<div id=\"image-container-1253810\" class=\"image-container\" style=\"float: none; margin: 45px 0px; width: 100%;\" data-midia=\"1253810\">\n<p><em>Vinicius Loures\/C\u00e2mara dos Deputados<\/em><\/p>\n<p>Laura Carneiro, relatora da proposta<\/p>\n<\/p><\/div>\n<p>A Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania da C\u00e2mara dos Deputados aprovou projeto de lei condicionando a revoga\u00e7\u00e3o de medidas protetivas de urg\u00eancia do agressor \u00e0 manifesta\u00e7\u00e3o pr\u00e9via da mulher v\u00edtima de viol\u00eancia dom\u00e9stica e familiar.<\/p>\n<p>Al\u00e9m disso, a proposta determina a realiza\u00e7\u00e3o da chamada audi\u00eancia de admoesta\u00e7\u00e3o para a soltura de agressor em caso de revoga\u00e7\u00e3o de pris\u00e3o preventiva. Nessa audi\u00eancia, o juiz dever\u00e1 advertir o agressor sobre a necessidade de cumprimento das medidas protetivas que lhe forem impostas. A audi\u00eancia dever\u00e1 ser realizada em at\u00e9 48 horas da decis\u00e3o de soltar o r\u00e9u. As medidas s\u00e3o inseridas na <a href=\"https:\/\/www2.camara.leg.br\/legin\/fed\/lei\/2006\/lei-11340-7-agosto-2006-545133-norma-pl.html\">Lei Maria da Penha<\/a>.<\/p>\n<p>Por recomenda\u00e7\u00e3o da relatora, deputada Laura Carneiro (PSD-RJ), foi aprovado o <span id=\"4098\" class=\"termoGlossario\" title=\"Nome que se d\u00e1 ao texto que altera substancialmente o conte\u00fado original da proposta. O substitutivo \u00e9 apresentado pelo relator e tem prefer\u00eancia na vota\u00e7\u00e3o sobre o projeto original.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">substitutivo<\/span> <a href=\"https:\/\/www.camara.leg.br\/noticias\/809810-COMISSAO-APROVA-PROPOSTA-QUE-CONDICIONA-REVOGACAO-DE-MEDIDAS-PROTETIVAS-A-OITIVA-PREVIA-DA-AGREDIDA\">da Comiss\u00e3o de Defesa dos Direitos da Mulher<\/a> ao <a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/545375-proposta-altera-lei-maria-da-penha-e-obriga-realizacao-de-audiencia-antes-de-soltura-de-agressor\">Projeto de Lei 10019\/18<\/a>, do Senado, e oito <span id=\"4069\" class=\"termoGlossario\" title=\"Projeto que tramita em conjunto com outro que trate de mat\u00e9ria semelhante. O relator deve analisar todas as proposi\u00e7\u00f5es apensadas, que dever\u00e3o constar do seu parecer.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">apensados<\/span> (PLs 2939\/15, 8320\/17, 3418\/19, 6010\/19, 1025\/21, 2454\/23, 3111\/23 e 5778\/23).<\/p>\n<p>Laura Carneiro defendeu que o contato com a v\u00edtima deve ser realizado pela equipe t\u00e9cnica da vara especializada, por equipamento da Rede de Enfrentamento \u00e0 Viol\u00eancia da regi\u00e3o de seu domic\u00edlio ou, ainda, pelo pr\u00f3prio ju\u00edzo da vara de viol\u00eancia dom\u00e9stica e familiar. &#8220;O que evitar\u00e1 o contato direto com o agressor e a poss\u00edvel revitimiza\u00e7\u00e3o da ofendida&#8221;, disse.<\/p>\n<p><strong>Medidas protetivas<\/strong><br \/>Entre as medidas protetivas previstas na Lei Maria da Penha, est\u00e3o a suspens\u00e3o do porte de arma, o afastamento do lar ou a proibi\u00e7\u00e3o de aproxima\u00e7\u00e3o da v\u00edtima.<\/p>\n<p>A pris\u00e3o preventiva \u00e9 aquela feita no curso da investiga\u00e7\u00e3o do crime, a fim de garantir a investiga\u00e7\u00e3o, impedir a fuga ou garantir a seguran\u00e7a das v\u00edtimas.<\/p>\n<p><strong>Pr\u00f3ximos passos<\/strong><br \/>Como a proposta foi alterada pela C\u00e2mara, ela retorna ao Senado. Para virar lei, precisa ser aprovada pelos deputados e pelos senadores.<\/p>\n<p style=\"font-size: 0.8rem; font-weight: 700;\">Reportagem &#8211; Tiago Miranda<br \/>Edi\u00e7\u00e3o &#8211; Marcia Becker<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1253612-comissao-aprova-protecao-a-mulheres-antes-de-revogar-medidas\/\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>16\/03\/2026 &#8211; 11:00 \u00a0 Vinicius Loures\/C\u00e2mara dos Deputados Laura Carneiro, relatora da proposta A Comiss\u00e3o de Constitui\u00e7\u00e3o e Justi\u00e7a e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5415,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[15],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/5414"}],"collection":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=5414"}],"version-history":[{"count":0,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/5414\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/5415"}],"wp:attachment":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=5414"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=5414"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=5414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}