{"id":5379,"date":"2026-03-13T19:47:24","date_gmt":"2026-03-13T22:47:24","guid":{"rendered":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/comissao-aprova-regras-para-busca-de-pessoas-com-deficiencia-noticias\/"},"modified":"2026-03-13T19:47:24","modified_gmt":"2026-03-13T22:47:24","slug":"comissao-aprova-regras-para-busca-de-pessoas-com-deficiencia-noticias","status":"publish","type":"post","link":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/comissao-aprova-regras-para-busca-de-pessoas-com-deficiencia-noticias\/","title":{"rendered":"Comiss\u00e3o aprova regras para busca de pessoas com defici\u00eancia &#8211; Not\u00edcias"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"g-artigo__data-hora\">\n                      13\/03\/2026 &#8211; 18:13 \u00a0\n                    <\/p>\n<div id=\"image-container-1253736\" class=\"image-container\" style=\"float: none; margin: 45px 0px; width: 100%;\" data-midia=\"1253736\">\n<p><em>Kayo Magalh\u00e3es \/ C\u00e2mara dos Deputados<\/em><\/p>\n<p>Deputado Capit\u00e3o Alden, relator do projeto de lei<\/p>\n<\/p><\/div>\n<p>A Comiss\u00e3o de Seguran\u00e7a P\u00fablica e Combate ao Crime Organizado da C\u00e2mara dos Deputados aprovou proposta que estabelece protocolos de busca e identifica\u00e7\u00e3o de pessoas com defici\u00eancia desaparecidas.<\/p>\n<p>Quando houver pessoa com defici\u00eancia desaparecida, suas necessidades espec\u00edficas dever\u00e3o ser consideradas na formula\u00e7\u00e3o de estrat\u00e9gia de busca, al\u00e9m de previsto acolhimento e aten\u00e7\u00e3o \u00e0 fam\u00edlia.<\/p>\n<p>O texto tamb\u00e9m prev\u00ea que as autoridades usem biometria ou outros recursos tecnol\u00f3gicos para ajudar a identificar e encontrar com mais rapidez o desaparecido.<\/p>\n<p>Nos casos de crian\u00e7as com defici\u00eancia desaparecidas, a pol\u00edcia garantir\u00e1 assist\u00eancia aos familiares.<\/p>\n<p><strong>Estrat\u00e9gia espec\u00edfica<\/strong><br \/>O projeto inclui as medidas no Estatuto da Crian\u00e7a e do Adolescente (ECA &#8211; <a class=\"linkLegislacao\" href=\"https:\/\/www2.camara.gov.br\/legin\/fed\/lei\/1990\/lei-8069-13-julho-1990-372211-norma-pl.html\">Lei 8.069\/90<\/a>) e na <a class=\"linkLegislacao\" href=\"https:\/\/www2.camara.gov.br\/legin\/fed\/lei\/2019\/lei-13812-16-marco-2019-787837-norma-pl.html\">Lei 13.812\/19<\/a>, que criou a Pol\u00edtica Nacional de Busca de Pessoas Desaparecidas.<\/p>\n<p>A proposta aprovada \u00e9 um <span id=\"4098\" class=\"termoGlossario\" title=\"Nome que se d\u00e1 ao texto que altera substancialmente o conte\u00fado original da proposta. O substitutivo \u00e9 apresentado pelo relator e tem prefer\u00eancia na vota\u00e7\u00e3o sobre o projeto original.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">substitutivo<\/span> do deputado Capit\u00e3o Alden (PL-BA) ao <a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1253424-projeto-cria-regras-para-busca-de-pessoas-com-deficiencia-desaparecidas\">Projeto de Lei 3794\/25<\/a>, do deputado Daniel Agrobom (PL-GO). O texto original n\u00e3o alterava o ECA e n\u00e3o previa biometria.<\/p>\n<p>Segundo Agrobom, a busca por pessoas com defici\u00eancia requer estrat\u00e9gias espec\u00edficas que levem em conta suas limita\u00e7\u00f5es e necessidades. &#8220;Pessoas com defici\u00eancia auditiva podem n\u00e3o responder a chamadas vocais, enquanto pessoas com defici\u00eancia visual podem se desorientar facilmente. A falta de uma abordagem especializada pode comprometer a efic\u00e1cia das buscas&#8221;, disse.<\/p>\n<p><strong>Comunica\u00e7\u00e3o<\/strong><br \/>Capit\u00e3o Alden afirmou que, quando o desaparecido \u00e9 uma pessoa com defici\u00eancia, a complexidade da investiga\u00e7\u00e3o aumenta devido a vulnerabilidades sensoriais ou de comunica\u00e7\u00e3o que podem impedir a v\u00edtima de pedir ajuda. De acordo com ele, a inclus\u00e3o da biometria \u00e9 um ponto de destaque.<\/p>\n<p>&#8220;Ao estabelecer o dever de priorizar meios tecnol\u00f3gicos de identifica\u00e7\u00e3o, o substitutivo fornece \u00e0s for\u00e7as policiais uma ferramenta de intelig\u00eancia que reduz o tempo de resposta e garante um desfecho seguro e c\u00e9lere para a ocorr\u00eancia&#8221;, declarou.<\/p>\n<p>Ele tamb\u00e9m enfatizou que, em muitos casos, a pessoa com defici\u00eancia localizada pode ter dificuldades de autogest\u00e3o ou comunica\u00e7\u00e3o, o que retarda sua identifica\u00e7\u00e3o.<\/p>\n<p><strong>Pr\u00f3ximos passos<\/strong><br \/>A proposta ainda ser\u00e1 analisada, em <span id=\"4322\" class=\"termoGlossario\" title=\"Rito de tramita\u00e7\u00e3o pelo qual o projeto \u00e9 votado apenas pelas comiss\u00f5es designadas para analis\u00e1-lo, dispensada a delibera\u00e7\u00e3o do Plen\u00e1rio. O projeto perde o car\u00e1ter conclusivo se houver decis\u00e3o divergente entre as comiss\u00f5es ou se, independentemente de ser aprovado ou rejeitado, houver recurso assinado por 52 deputados para a aprecia\u00e7\u00e3o da mat\u00e9ria no Plen\u00e1rio.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">car\u00e1ter conclusivo<\/span>, pelas comiss\u00f5es de Defesa dos Direitos das Pessoas com Defici\u00eancia; e de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania. Para virar lei, precisa ser aprovada pela C\u00e2mara e pelo Senado.<\/p>\n<p style=\"font-size: 0.8rem; font-weight: 700;\">Reportagem \u2013 Tiago Miranda<br \/>Edi\u00e7\u00e3o \u2013 Roberto Seabra<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1253715-comissao-aprova-regras-para-busca-de-pessoas-com-deficiencia\/\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>13\/03\/2026 &#8211; 18:13 \u00a0 Kayo Magalh\u00e3es \/ C\u00e2mara dos Deputados Deputado Capit\u00e3o Alden, relator do projeto de lei A Comiss\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5380,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[20],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/5379"}],"collection":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=5379"}],"version-history":[{"count":0,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/5379\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/5380"}],"wp:attachment":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=5379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=5379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=5379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}