{"id":5317,"date":"2026-03-11T23:39:06","date_gmt":"2026-03-12T02:39:06","guid":{"rendered":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/entidades-propoem-saneamento-basico-com-controle-social-e-adaptacao-as-mudancas-climaticas-noticias\/"},"modified":"2026-03-11T23:39:06","modified_gmt":"2026-03-12T02:39:06","slug":"entidades-propoem-saneamento-basico-com-controle-social-e-adaptacao-as-mudancas-climaticas-noticias","status":"publish","type":"post","link":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/entidades-propoem-saneamento-basico-com-controle-social-e-adaptacao-as-mudancas-climaticas-noticias\/","title":{"rendered":"Entidades prop\u00f5em saneamento b\u00e1sico com controle social e adapta\u00e7\u00e3o \u00e0s mudan\u00e7as clim\u00e1ticas &#8211; Not\u00edcias"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<p class=\"g-artigo__data-hora\">\n                      11\/03\/2026 &#8211; 19:58 \u00a0\n                    <\/p>\n<div id=\"image-container-1252751\" class=\"image-container\" style=\"float: none; margin: 45px 0px; width: 100%;\" data-midia=\"1252751\">\n<p><em>Renato Ara\u00fajo \/ C\u00e2mara dos Deputados<\/em><\/p>\n<p>Semin\u00e1rio foi realizado pela CLP, com o apoio de frente parlamentar<\/p>\n<\/p><\/div>\n<p>O Observat\u00f3rio Nacional dos Direitos \u00e0 \u00c1gua e ao Saneamento, formado por v\u00e1rias entidades da sociedade civil, prop\u00f4s uma s\u00e9rie de mudan\u00e7as nas leis que tratam do saneamento b\u00e1sico, durante semin\u00e1rio na C\u00e2mara dos Deputados nesta quarta-feira (11).<\/p>\n<p>As sugest\u00f5es <a href=\"https:\/\/www.camara.leg.br\/proposicoesWeb\/fichadetramitacao?idProposicao=2608063\">(SUG 3\/26<\/a>) foram protocoladas na Comiss\u00e3o de Legisla\u00e7\u00e3o Participativa (CLP) com apoio da Frente Parlamentar em Defesa do Saneamento P\u00fablico, com o objetivo de virarem projeto de lei de iniciativa popular.<\/p>\n<p>Integram o texto temas como freio na privatiza\u00e7\u00e3o dos servi\u00e7os de \u00e1gua pot\u00e1vel e esgotamento sanit\u00e1rio, garantia de controle social e adapta\u00e7\u00e3o do saneamento \u00e0s mudan\u00e7as clim\u00e1ticas, como explica F\u00e1bio Giori, representante do Coletivo Nacional do Saneamento.<\/p>\n<p>\u201cEsse projeto de lei vem, na verdade, ser um grito de socorro da sociedade civil organizada na defesa da universaliza\u00e7\u00e3o do servi\u00e7o de saneamento, para que a gente possa ter investimento nas \u00e1reas de periferia, para que seja criado um fundo de universaliza\u00e7\u00e3o do setor\u201d, disse.<\/p>\n<p>Durante o semin\u00e1rio organizado pela frente parlamentar, os representantes das entidades da sociedade civil criticaram v\u00e1rios pontos do novo marco do saneamento b\u00e1sico (<a class=\"linkLegislacao\" href=\"https:\/\/www2.camara.gov.br\/legin\/fed\/lei\/2020\/lei-14026-15-julho-2020-790419-norma-pl.html\">Lei 14.026\/20<\/a>). Acrescentaram que a lei foi aprovada pelo Congresso durante a pandemia de Covid-19, sem o devido debate com a popula\u00e7\u00e3o. Houve palavras de ordem contra o que chamam de \u201cprivatiza\u00e7\u00e3o dos servi\u00e7os\u201d por meio de concess\u00f5es, parcerias p\u00fablico-privadas e venda de companhias estaduais.<\/p>\n<p>Integrante do Observat\u00f3rio Nacional dos Direitos \u00e0 \u00c1gua e ao Saneamento, Edson Aparecido avalia que a lei tem levado \u00e0 \u201coligopoliza\u00e7\u00e3o\u201d do setor.\u00a0 \u201cHoje, apenas cinco empresas privadas no Brasil controlam 95% do saneamento privado. E outro impacto importante desse processo de privatiza\u00e7\u00e3o tem sido a queda na qualidade de servi\u00e7os e aumento brutal das tarifas\u201d, afirmou.<\/p>\n<p><strong>Desigualdade<\/strong><br \/>O coordenador da frente parlamentar, deputado Joseildo Ramos (PT-BA), j\u00e1 havia encampado outra proposta (<a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/898890-projeto-prioriza-acesso-a-agua-e-ao-esgoto-sanitario-como-direitos-humanos\">PL 1922\/22<\/a>) da sociedade civil para ajustar a legisla\u00e7\u00e3o, mas o texto ainda aguarda vota\u00e7\u00e3o na Comiss\u00e3o de Defesa do Consumidor. Joseildo cita outros motivos que justificam mudan\u00e7as no marco legal do saneamento b\u00e1sico.<\/p>\n<p>\u201cO servi\u00e7o p\u00fablico que mais denuncia a desigualdade \u00e9 o saneamento. Se voc\u00ea vai para as periferias das nossas cidades, o lugar onde n\u00e3o tem saneamento b\u00e1sico \u00e9 exatamente onde est\u00e1 a pobreza. E outra: em \u00e9pocas de rigores clim\u00e1ticos, ou a gente faz alguma coisa ou ent\u00e3o n\u00e3o sobra para ningu\u00e9m. As estruturas de saneamento t\u00eam que ser repensadas\u201d, enfatizou.<\/p>\n<p>Os participantes do semin\u00e1rio ainda criticaram o <span id=\"4309\" class=\"termoGlossario\" title=\"Banco federal que disponibiliza linhas de financiamento de longo prazo para empresas, com taxas de juros especiais. \u00c9 o principal agente financiador, entre os bancos, de projetos de infraestrutura.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">BNDES<\/span> pelos financiamentos liberados para empresas que atuam no setor com aporte de fundos de investimento e de grandes grupos privados.<\/p>\n<p style=\"font-size: 0.8rem; font-weight: 700;\">Reportagem \u2013 \u00a0Jos\u00e9 Carlos Oliveira<br \/>Edi\u00e7\u00e3o \u2013 Ana Chalub<\/p>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1252738-entidades-propoem-saneamento-basico-com-controle-social-e-adaptacao-as-mudancas-climaticas\/\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>11\/03\/2026 &#8211; 19:58 \u00a0 Renato Ara\u00fajo \/ C\u00e2mara dos Deputados Semin\u00e1rio foi realizado pela CLP, com o apoio de frente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5318,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[10],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/5317"}],"collection":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=5317"}],"version-history":[{"count":0,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/5317\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/5318"}],"wp:attachment":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=5317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=5317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=5317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}