{"id":5070,"date":"2026-02-13T03:22:24","date_gmt":"2026-02-13T06:22:24","guid":{"rendered":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/comissao-aprova-projeto-que-cria-programa-para-subsidiar-compra-de-armamento-noticias\/"},"modified":"2026-02-13T03:22:24","modified_gmt":"2026-02-13T06:22:24","slug":"comissao-aprova-projeto-que-cria-programa-para-subsidiar-compra-de-armamento-noticias","status":"publish","type":"post","link":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/comissao-aprova-projeto-que-cria-programa-para-subsidiar-compra-de-armamento-noticias\/","title":{"rendered":"Comiss\u00e3o aprova projeto que cria programa para subsidiar compra de armamento &#8211; Not\u00edcias"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<div>\n<p class=\"g-artigo__data-hora\">\n                      11\/02\/2026 &#8211; 14:41 \u00a0\n                    <\/p>\n<div id=\"image-container-1244787\" class=\"image-container\" style=\"float: none; margin: 45px 0px; width: 100%;\" data-midia=\"1244787\">\n<p><em>Kayo Magalh\u00e3es \/ C\u00e2mara dos Deputados<\/em><\/p>\n<p>Zucco \u00e9 o relator do projeto<\/p>\n<\/p><\/div>\n<p>A Comiss\u00e3o de Seguran\u00e7a P\u00fablica da C\u00e2mara dos Deputados aprovou projeto de lei que cria a Pol\u00edtica Nacional de Acesso \u00e0 Primeira Arma de Fogo. A ideia \u00e9 facilitar, por meio da isen\u00e7\u00e3o de tributos federais e de linhas de cr\u00e9dito espec\u00edficas, a aquisi\u00e7\u00e3o de armamento para quem cumprir os requisitos legais.<\/p>\n<p>O texto isenta a compra do Imposto sobre <span id=\"4186\" class=\"termoGlossario\" title=\"Imposto sobre Produtos Industrializados (IPI): Imposto cobrado pelo governo federal que incide sobre os produtos fabricados no Pa\u00eds ou importados. A al\u00edquota varia conforme o produto.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">Produtos Industrializados<\/span> (IPI), do <span id=\"4491\" class=\"termoGlossario\" title=\"Imposto federal que incide sobre a importa\u00e7\u00e3o de mercadorias estrangeiras e sobre produtos comprados por turistas que chegam do exterior.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">Imposto de Importa\u00e7\u00e3o<\/span> (II) e das contribui\u00e7\u00f5es sociais <span id=\"4110\" class=\"termoGlossario\" title=\"O Programa de Integra\u00e7\u00e3o Social (PIS) e o Programa de Forma\u00e7\u00e3o do Patrim\u00f4nio do Servidor P\u00fablico (Pasep) formam um \u00fanico fundo mantido pelas pessoas jur\u00eddicas, com exce\u00e7\u00e3o das micro e pequenas empresas optantes pelo regime tribut\u00e1rio Simples Nacional. As al\u00edquotas das contribui\u00e7\u00f5es variam de 0,65% a 1,65% sobre o total das receitas. Esses recursos s\u00e3o destinados aos trabalhadores em forma de rendimentos ou abonos salariais.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">PIS\/Pasep<\/span> e <span id=\"4104\" class=\"termoGlossario\" title=\"Tributo que incide sobre a receita das pessoas jur\u00eddicas de direito privado, exceto as empresas submetidas ao Simples Nacional. Os recursos arrecadados s\u00e3o exclusivos da Uni\u00e3o e destinam-se ao financiamento da sa\u00fade, previd\u00eancia e assist\u00eancia social.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">Cofins<\/span>. A proposta tamb\u00e9m autoriza subs\u00eddios parciais ou integrais, conforme a renda do interessado, e financiamento com taxas favorecidas em bancos p\u00fablicos.<\/p>\n<p><strong>Crit\u00e9rios e prioridades<\/strong><br \/>Para participar do programa, o cidad\u00e3o interessado deve ter a idade m\u00ednima exigida em lei, estar em situa\u00e7\u00e3o regular com a Receita Federal e n\u00e3o possuir registro anterior de arma nos sistemas oficiais. Tamb\u00e9m ser\u00e1 necess\u00e1rio apresentar a autoriza\u00e7\u00e3o v\u00e1lida expedida pela Pol\u00edcia Federal ou pelo Ex\u00e9rcito.<\/p>\n<p>O substitutivo define grupos priorit\u00e1rios para atendimento no programa, como:<\/p>\n<ul>\n<li>v\u00edtimas de viol\u00eancia dom\u00e9stica com medida protetiva;<\/li>\n<li>v\u00edtimas de crimes contra a vida ou contra o patrim\u00f4nio;<\/li>\n<li>moradores de zonas rurais; e<\/li>\n<li>pessoas com renda familiar mensal de at\u00e9 cinco sal\u00e1rios m\u00ednimos (R$ 8.105, atualmente).<\/li>\n<\/ul>\n<p>A proposta aprovada \u00e9 o <span id=\"4098\" class=\"termoGlossario\" title=\"Nome que se d\u00e1 ao texto que altera substancialmente o conte\u00fado original da proposta. O substitutivo \u00e9 apresentado pelo relator e tem prefer\u00eancia na vota\u00e7\u00e3o sobre o projeto original.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">substitutivo<\/span> do relator, deputado Zucco (PL-RS), para o <a class=\"linkProposicao\" href=\"https:\/\/www.camara.leg.br\/noticias\/1244726-projeto-cria-programa-para-subsidiar-compra-de-armamento\">Projeto de Lei 2959\/25<\/a>, do deputado Marcos Pollon (PL-MS).<\/p>\n<p>\u201cEsta iniciativa dever\u00e1 promover a democratiza\u00e7\u00e3o do acesso \u00e0 leg\u00edtima defesa, respeitados os crit\u00e9rios de seguran\u00e7a, legalidade e responsabilidade individual\u201d, afirmou Zucco no parecer aprovado.<\/p>\n<p><strong>Pr\u00f3ximos passos<\/strong><br \/>A proposta tramita em <span id=\"4322\" class=\"termoGlossario\" title=\"Rito de tramita\u00e7\u00e3o pelo qual o projeto \u00e9 votado apenas pelas comiss\u00f5es designadas para analis\u00e1-lo, dispensada a delibera\u00e7\u00e3o do Plen\u00e1rio. O projeto perde o car\u00e1ter conclusivo se houver decis\u00e3o divergente entre as comiss\u00f5es ou se, independentemente de ser aprovado ou rejeitado, houver recurso assinado por 52 deputados para a aprecia\u00e7\u00e3o da mat\u00e9ria no Plen\u00e1rio.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">car\u00e1ter conclusivo<\/span> e ainda ser\u00e1 analisada pelas comiss\u00f5es de Finan\u00e7as e Tributa\u00e7\u00e3o; e de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania. Para virar lei, o texto ter\u00e1 de ser aprovado pela C\u00e2mara e pelo Senado.<\/p>\n<p style=\"font-size: 0.8rem; font-weight: 700;\">Da Reportagem\/RM<br \/>Edi\u00e7\u00e3o \u2013 Rachel Librelon<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1244732-comissao-aprova-projeto-que-cria-programa-para-subsidiar-compra-de-armamento\/\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>11\/02\/2026 &#8211; 14:41 \u00a0 Kayo Magalh\u00e3es \/ C\u00e2mara dos Deputados Zucco \u00e9 o relator do projeto A Comiss\u00e3o de Seguran\u00e7a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5071,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[15],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/5070"}],"collection":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=5070"}],"version-history":[{"count":0,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/5070\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/5071"}],"wp:attachment":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=5070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=5070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=5070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}