{"id":5068,"date":"2026-02-13T01:20:51","date_gmt":"2026-02-13T04:20:51","guid":{"rendered":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/projeto-cria-programa-para-subsidiar-compra-de-arma-de-fogo-noticias\/"},"modified":"2026-02-13T01:20:51","modified_gmt":"2026-02-13T04:20:51","slug":"projeto-cria-programa-para-subsidiar-compra-de-arma-de-fogo-noticias","status":"publish","type":"post","link":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/projeto-cria-programa-para-subsidiar-compra-de-arma-de-fogo-noticias\/","title":{"rendered":"Projeto cria programa para subsidiar compra de arma de fogo &#8211; Not\u00edcias"},"content":{"rendered":"<p> <br \/>\n<\/p>\n<div>\n<div>\n<p class=\"g-artigo__data-hora\">\n                      11\/02\/2026 &#8211; 14:48 \u00a0\n                    <\/p>\n<div id=\"image-container-1244779\" class=\"image-container\" style=\"float: none; margin: 45px 0px; width: 100%;\" data-midia=\"1244779\">\n<p><em>Zeca Ribeiro \/ C\u00e2mara dos Deputados<\/em><\/p>\n<p>Marcos Pollon \u00e9 o autor do projeto<\/p>\n<\/p><\/div>\n<p>O Projeto de Lei 2959\/25 institui o Programa Minha Primeira Arma, para facilitar a aquisi\u00e7\u00e3o da primeira arma de fogo por cidad\u00e3os que cumpram os requisitos legais. O texto prev\u00ea isen\u00e7\u00e3o de tributos federais e linhas de cr\u00e9dito espec\u00edficas.<\/p>\n<p>Conforme a proposta em an\u00e1lise na C\u00e2mara dos Deputados, o programa oferecer\u00e1 isen\u00e7\u00e3o de <span id=\"4186\" class=\"termoGlossario\" title=\"Imposto sobre Produtos Industrializados (IPI): Imposto cobrado pelo governo federal que incide sobre os produtos fabricados no Pa\u00eds ou importados. A al\u00edquota varia conforme o produto.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">Imposto sobre Produtos Industrializados<\/span> (IPI), <span id=\"4491\" class=\"termoGlossario\" title=\"Imposto federal que incide sobre a importa\u00e7\u00e3o de mercadorias estrangeiras e sobre produtos comprados por turistas que chegam do exterior.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">Imposto de Importa\u00e7\u00e3o<\/span> (II) e contribui\u00e7\u00f5es sociais (PIS\/Cofins) incidentes sobre a compra.<\/p>\n<p>Al\u00e9m disso, o projeto autoriza a concess\u00e3o de subs\u00eddios parciais ou integrais, dependendo da faixa de renda do requerente, e financiamento com taxas favorecidas em bancos p\u00fablicos.<\/p>\n<p>Autor da proposta, o deputado Marcos Pollon (PL-MS) afirmou que a atual carga tribut\u00e1ria dificulta o acesso a meios de defesa. \u201cSe o Estado reconhece o direito de defesa como leg\u00edtimo, deve remover as barreiras para seu exerc\u00edcio\u201d, avaliou.<\/p>\n<p><strong>Crit\u00e9rios e prioridades<\/strong><br \/>Para participar do futuro programa, o cidad\u00e3o interessado deve ter a idade m\u00ednima exigida em lei, estar em situa\u00e7\u00e3o regular com a Receita Federal e n\u00e3o possuir registro anterior de arma nos sistemas oficiais. Tamb\u00e9m ser\u00e1 necess\u00e1rio apresentar a autoriza\u00e7\u00e3o v\u00e1lida expedida pela Pol\u00edcia Federal ou pelo Ex\u00e9rcito.<\/p>\n<p>A proposta define grupos priorit\u00e1rios para atendimento no programa, como:<\/p>\n<ul>\n<li>v\u00edtimas de viol\u00eancia dom\u00e9stica com medida protetiva;<\/li>\n<li>v\u00edtimas de crimes contra a vida ou contra o patrim\u00f4nio;<\/li>\n<li>moradores de zonas rurais; e<\/li>\n<li>pessoas com renda familiar mensal de at\u00e9 cinco sal\u00e1rios m\u00ednimos (R$ 8.105, atualmente).<\/li>\n<\/ul>\n<p><strong>Pr\u00f3ximos passos<\/strong><br \/>A proposta tramita em <span id=\"4322\" class=\"termoGlossario\" title=\"Rito de tramita\u00e7\u00e3o pelo qual o projeto \u00e9 votado apenas pelas comiss\u00f5es designadas para analis\u00e1-lo, dispensada a delibera\u00e7\u00e3o do Plen\u00e1rio. O projeto perde o car\u00e1ter conclusivo se houver decis\u00e3o divergente entre as comiss\u00f5es ou se, independentemente de ser aprovado ou rejeitado, houver recurso assinado por 52 deputados para a aprecia\u00e7\u00e3o da mat\u00e9ria no Plen\u00e1rio.\" contenteditable=\"false\" data-toggle=\"tooltip\" data-placement=\"top\">car\u00e1ter conclusivo<\/span> e ser\u00e1 analisada pelas comiss\u00f5es de Seguran\u00e7a P\u00fablica e Combate ao Crime Organizado; de Finan\u00e7as e Tributa\u00e7\u00e3o; e de Constitui\u00e7\u00e3o e Justi\u00e7a e de Cidadania.<\/p>\n<p>Para virar lei, o texto ter\u00e1 de ser aprovado pela C\u00e2mara e pelo Senado.<\/p>\n<p><a href=\"https:\/\/www.camara.leg.br\/noticias\/573454-SAIBA-MAIS-SOBRE-A-TRAMITACAO-DE-PROJETOS-DE-LEI\">Saiba mais sobre a tramita\u00e7\u00e3o de projetos de lei<\/a><\/p>\n<p style=\"font-size: 0.8rem; font-weight: 700;\">Da Reportagem\/RM<br \/>Edi\u00e7\u00e3o \u2013 Rachel Librelon<\/p>\n<\/p><\/div>\n<\/p><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.camara.leg.br\/noticias\/1244726-projeto-cria-programa-para-subsidiar-compra-de-arma-de-fogo\/\">postagem original <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>11\/02\/2026 &#8211; 14:48 \u00a0 Zeca Ribeiro \/ C\u00e2mara dos Deputados Marcos Pollon \u00e9 o autor do projeto O Projeto de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5069,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[15],"tags":[],"_links":{"self":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/5068"}],"collection":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/comments?post=5068"}],"version-history":[{"count":0,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/posts\/5068\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media\/5069"}],"wp:attachment":[{"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/media?parent=5068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/categories?post=5068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/radiosaojoaquim.sitetopfm.com.br\/site\/wp-json\/wp\/v2\/tags?post=5068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}